{"id":4,"date":"2016-09-17T08:30:11","date_gmt":"2016-09-17T08:30:11","guid":{"rendered":"http:\/\/demo.weblizar.com\/corporal-premium\/cart\/"},"modified":"2016-09-17T08:30:11","modified_gmt":"2016-09-17T08:30:11","slug":"cart","status":"publish","type":"page","link":"https:\/\/demo.weblizar.com\/corporal-premium\/cart\/","title":{"rendered":"Cart"},"content":{"rendered":"<p>[woocommerce_cart]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[woocommerce_cart]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/demo.weblizar.com\/corporal-premium\/wp-json\/wp\/v2\/pages\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demo.weblizar.com\/corporal-premium\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demo.weblizar.com\/corporal-premium\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demo.weblizar.com\/corporal-premium\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.weblizar.com\/corporal-premium\/wp-json\/wp\/v2\/comments?post=4"}],"version-history":[{"count":0,"href":"https:\/\/demo.weblizar.com\/corporal-premium\/wp-json\/wp\/v2\/pages\/4\/revisions"}],"wp:attachment":[{"href":"https:\/\/demo.weblizar.com\/corporal-premium\/wp-json\/wp\/v2\/media?parent=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}